{"id":53172,"date":"2025-10-23T17:21:11","date_gmt":"2025-10-23T21:21:11","guid":{"rendered":"https:\/\/jesusreyeslaw.com\/?p=53172"},"modified":"2025-10-23T17:25:30","modified_gmt":"2025-10-23T21:25:30","slug":"tps-venezuela-drivers-license-in-florida","status":"publish","type":"post","link":"https:\/\/jesusreyeslaw.com\/en\/tps-venezuela-drivers-license-in-florida\/","title":{"rendered":"TPS Venezuela: \u0003Driver\u2019s License in florida"},"content":{"rendered":"<p><span data-buffer=\"&lt;!--(Adobe)%7B%22type%22%3A%22horizonObject%22%2C%22payload%22%3A%7B%22docId%22%3A%22urn%3Aaaid%3Asc%3AUS%3A8681444c-8303-573a-b790-8847c2c7c635%22%2C%22repositoryId%22%3A%22urn%3Aaaid%3Asc%3AUS%3A7f347c18-c8a3-52e5-8bb6-5722e61eca28%22%2C%22copyClientId%22%3A%227e93896b-cf25-4627-a556-963a884a22fc%22%2C%22docModel%22%3A%7B%22isFullDocument%22%3Afalse%2C%22serializedECS%22%3A%7B%22AssetInfo%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22BitmapReference%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ForwardReference%22%3A%7B%7D%7D%2C%22BitmapRole%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22BlendMode%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22CanvasColor%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ContentCredentialsMetadata%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22LinkedAssetMetadata%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22EllipseGeometry%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22FillChildOf%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ChildOf%22%3A%7B%7D%7D%2C%22FillColor%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22IsColor%22%3A%7B%7D%7D%2C%22FillTransform%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22FillType%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ImageSaliencyMetadata%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22InvisibleBoundingBox%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22IsCropGroup%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22LineGeometry%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22MarkedForImport%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ObjectFit%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22PixelInformation%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22RectangleCornerRadii%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22RectangleGeometry%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceAvailability%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceHasCaiData%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceChildOf%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ChildOf%22%3A%7B%7D%7D%2C%22ResourceCollectionChildOf%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ChildOf%22%3A%7B%7D%2C%22WeakChildOf%22%3A%7B%7D%7D%2C%22ResourceCollectionInfo%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceCollectionOriginalContentHashSHA1%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceCollectionOriginalFileName%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceCollectionOriginalMimeType%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceCollectionOriginalResourceSize%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceDimensions%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceInfo%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceNeedsPublishing%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourcePreferredPixelFormat%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceUrl%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeAspectLock%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeChildOf%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ChildOf%22%3A%7B%7D%7D%2C%22SceneNodeLockCurrent%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22AffectsEditabilityTrait%22%3A%7B%7D%7D%2C%22SceneNodeLockMinimum%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeName%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeOpacity%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeTransform%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeType%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22slot%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeCap%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeChildOf%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ChildOf%22%3A%7B%7D%7D%2C%22StrokeColor%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22IsColor%22%3A%7B%7D%7D%2C%22StrokeDashGeometry%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeJoin%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeMiter%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokePosition%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeType%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeWidth%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SourceAssetIdentifier%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22TimingInfo%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22VisibleBoundingBox%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22XMPMetadata%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22BatchCreateDataMapping%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeAncestorLockState%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22AffectsEditabilityTrait%22%3A%7B%7D%7D%2C%22%23decoration%22%3A%7B%22NonPersistable%22%3A%7B%7D%7D%2C%22%23canvas%22%3A%7B%22NonPersistable%22%3A%7B%7D%7D%2C%22%23effects%22%3A%7B%22NonPersistable%22%3A%7B%7D%7D%2C%22ResourceIsUploading%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22PendingSave%22%3A%7B%7D%7D%2C%22ResourceCollectionIsStoringInIDB%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22PendingSave%22%3A%7B%7D%7D%2C%22001d4d83-3ea1-43f6-a575-b09949bcf7de%22%3A%7B%22SceneNodeTransform%22%3A%7B%22x%22%3A135.7041015625%2C%22y%22%3A580.7243041992188%2C%22rotation%22%3A0%2C%22scaleX%22%3A1.3333333333333333%2C%22scaleY%22%3A1.3333333333333333%7D%2C%22SceneNodeType%22%3A%7B%22type%22%3A%22Text%22%7D%2C%22TextType%22%3A%7B%22allowMultiframe%22%3Afalse%7D%2C%22TextAlignment%22%3A%7B%22alignment%22%3A1%7D%2C%22TextGeometry%22%3A%7B%22type%22%3A2%2C%22damaged%22%3Atrue%2C%22width%22%3A519.093994140625%2C%22height%22%3A351.1644287109375%2C%22baselineOffset%22%3A0%7D%2C%22TextModel%22%3A%7B%22text%22%3A%22Miami-Dade%20Tax%20Collector%20Dariel%20Fernandez%20has%20announced%20new%20guidelines%20for%20driver%E2%80%99s%20licenses%20for%20Venezuelan%20citizens%20under%20TPS%2C%20as%20outlined%20by%20the%20Florida%20Department%20of%20Highway%20Safety%20and%20Motor%20Vehicles.%5Cu0003%5CrBe%20sure%20to%20check%20the%20key%20dates%20listed%20on%20your%20work%20permit%20or%20immigration%20notice.%22%2C%22styles%22%3A%7B%22ranges%22%3A%5B%7B%22charStyle%22%3A%7B%22assigned%22%3A493%2C%22font%22%3A%7B%22source%22%3A%22AF%22%2C%22id%22%3A%22TkD-37516-9d7b232dfcf705029e0147542746f012c505492a%22%2C%22postscriptName%22%3A%22Poppins-Regular%22%2C%22family%22%3A%22Poppins%22%2C%22style%22%3A%22Regular%22%7D%2C%22originalFont%22%3A%7B%22source%22%3A%22AF%22%2C%22id%22%3A%22TkD-37516-9d7b232dfcf705029e0147542746f012c505492a%22%2C%22postscriptName%22%3A%22Poppins-Regular%22%2C%22family%22%3A%22Poppins%22%2C%22style%22%3A%22Regular%22%7D%2C%22fontSize%22%3A28.786354064941406%2C%22color%22%3A%7B%22a%22%3A1%2C%22r%22%3A1%2C%22g%22%3A1%2C%22b%22%3A1%7D%2C%22strikethrough%22%3Afalse%2C%22tracking%22%3A0%2C%22underline%22%3Afalse%2C%22features%22%3A%5B%5D%2C%22textScript%22%3A0%7D%2C%22length%22%3A285%7D%5D%2C%22paragraphs%22%3A%5B%7B%22style%22%3A%7B%22leading%22%3A%7B%22amount%22%3A1.100000023841858%2C%22type%22%3A1%7D%2C%22listStyle%22%3A%7B%22listId%22%3A%22%22%2C%22listLevel%22%3A0%7D%2C%22direction%22%3A0%2C%22spaceAfter%22%3A0%2C%22spaceBefore%22%3A0%2C%22assigned%22%3A15%7D%2C%22length%22%3A204%7D%2C%7B%22style%22%3A%7B%22leading%22%3A%7B%22amount%22%3A1.100000023841858%2C%22type%22%3A1%7D%2C%22listStyle%22%3A%7B%22listId%22%3A%22%22%2C%22listLevel%22%3A0%7D%2C%22direction%22%3A0%2C%22spaceAfter%22%3A0%2C%22spaceBefore%22%3A0%2C%22assigned%22%3A15%7D%2C%22length%22%3A1%7D%2C%7B%22style%22%3A%7B%22leading%22%3A%7B%22amount%22%3A1.100000023841858%2C%22type%22%3A1%7D%2C%22listStyle%22%3A%7B%22listId%22%3A%22%22%2C%22listLevel%22%3A0%7D%2C%22direction%22%3A0%2C%22spaceAfter%22%3A0%2C%22spaceBefore%22%3A0%2C%22assigned%22%3A15%7D%2C%22length%22%3A80%7D%5D%2C%22listStyles%22%3A%5B%5D%7D%2C%22objectStyle%22%3A%7B%22languageLayoutProfile%22%3A%7B%22name%22%3A%22langDefault%22%2C%22version%22%3A1%7D%7D%7D%2C%22TextDefaultValueChanged%22%3A%7B%7D%2C%22TextForwardReferencesMap%22%3A%7B%22entityIdMapping%22%3A%7B%7D%7D%2C%22ArtboardRelativeSceneNodeTransform%22%3A%7B%22x%22%3A135.7041015625%2C%22y%22%3A580.7243041992188%2C%22rotation%22%3A0%7D%2C%22CopyPastePixelInformation%22%3A%7B%22density%22%3A96%7D%7D%7D%2C%22version%22%3A360%2C%22draftDocumentModels%22%3A%22%22%7D%2C%22entityIds%22%3A%5B%22001d4d83-3ea1-43f6-a575-b09949bcf7de%22%5D%7D%2C%22metadata%22%3A%7B%22sourceContext%22%3A%22af40f528-6877-4bc9-9663-809d34fbbd76%22%7D%7D(\/Adobe)--&gt;\">Miami-Dade Tax Collector Dariel Fernandez has announced new guidelines for driver\u2019s licenses for Venezuelan citizens under TPS, as outlined by the Florida Department of Highway Safety and Motor Vehicles.\u0003 Be sure to check the key dates listed on your work permit or immigration notice.<\/span><\/p>\n<h2><span data-buffer=\"&lt;!--(Adobe)%7B%22type%22%3A%22horizonObject%22%2C%22payload%22%3A%7B%22docId%22%3A%22urn%3Aaaid%3Asc%3AUS%3A8681444c-8303-573a-b790-8847c2c7c635%22%2C%22repositoryId%22%3A%22urn%3Aaaid%3Asc%3AUS%3A7f347c18-c8a3-52e5-8bb6-5722e61eca28%22%2C%22copyClientId%22%3A%227e93896b-cf25-4627-a556-963a884a22fc%22%2C%22docModel%22%3A%7B%22isFullDocument%22%3Afalse%2C%22serializedECS%22%3A%7B%22AssetInfo%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22BitmapReference%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ForwardReference%22%3A%7B%7D%7D%2C%22BitmapRole%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22BlendMode%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22CanvasColor%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ContentCredentialsMetadata%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22LinkedAssetMetadata%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22EllipseGeometry%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22FillChildOf%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ChildOf%22%3A%7B%7D%7D%2C%22FillColor%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22IsColor%22%3A%7B%7D%7D%2C%22FillTransform%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22FillType%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ImageSaliencyMetadata%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22InvisibleBoundingBox%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22IsCropGroup%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22LineGeometry%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22MarkedForImport%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ObjectFit%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22PixelInformation%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22RectangleCornerRadii%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22RectangleGeometry%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceAvailability%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceHasCaiData%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceChildOf%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ChildOf%22%3A%7B%7D%7D%2C%22ResourceCollectionChildOf%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ChildOf%22%3A%7B%7D%2C%22WeakChildOf%22%3A%7B%7D%7D%2C%22ResourceCollectionInfo%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceCollectionOriginalContentHashSHA1%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceCollectionOriginalFileName%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceCollectionOriginalMimeType%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceCollectionOriginalResourceSize%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceDimensions%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceInfo%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceNeedsPublishing%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourcePreferredPixelFormat%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceUrl%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeAspectLock%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeChildOf%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ChildOf%22%3A%7B%7D%7D%2C%22SceneNodeLockCurrent%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22AffectsEditabilityTrait%22%3A%7B%7D%7D%2C%22SceneNodeLockMinimum%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeName%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeOpacity%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeTransform%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeType%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22slot%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeCap%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeChildOf%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ChildOf%22%3A%7B%7D%7D%2C%22StrokeColor%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22IsColor%22%3A%7B%7D%7D%2C%22StrokeDashGeometry%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeJoin%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeMiter%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokePosition%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeType%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeWidth%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SourceAssetIdentifier%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22TimingInfo%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22VisibleBoundingBox%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22XMPMetadata%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22BatchCreateDataMapping%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeAncestorLockState%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22AffectsEditabilityTrait%22%3A%7B%7D%7D%2C%22%23decoration%22%3A%7B%22NonPersistable%22%3A%7B%7D%7D%2C%22%23canvas%22%3A%7B%22NonPersistable%22%3A%7B%7D%7D%2C%22%23effects%22%3A%7B%22NonPersistable%22%3A%7B%7D%7D%2C%22ResourceIsUploading%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22PendingSave%22%3A%7B%7D%7D%2C%22ResourceCollectionIsStoringInIDB%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22PendingSave%22%3A%7B%7D%7D%2C%22de50cee4-0ae2-4c31-8194-3c59572e4f45%22%3A%7B%22SceneNodeTransform%22%3A%7B%22x%22%3A333.0556640625%2C%22y%22%3A451.0825500488281%2C%22rotation%22%3A0%2C%22scaleX%22%3A1.3333333333333333%2C%22scaleY%22%3A1.3333333333333333%7D%2C%22SceneNodeType%22%3A%7B%22type%22%3A%22Text%22%7D%2C%22TextType%22%3A%7B%22allowMultiframe%22%3Afalse%7D%2C%22TextAlignment%22%3A%7B%22alignment%22%3A3%7D%2C%22TextGeometry%22%3A%7B%22type%22%3A2%2C%22damaged%22%3Atrue%2C%22width%22%3A467.70086669921875%2C%22height%22%3A226.4993133544922%2C%22baselineOffset%22%3A0%7D%2C%22TextModel%22%3A%7B%22text%22%3A%22Licenses%20valid%20until%5Cr%20October%202026%22%2C%22styles%22%3A%7B%22ranges%22%3A%5B%7B%22charStyle%22%3A%7B%22assigned%22%3A493%2C%22font%22%3A%7B%22source%22%3A%22AF%22%2C%22id%22%3A%22TkD-37900-2fcb08c1acb10c553a809c1b259a7f5ebaa037cc%22%2C%22postscriptName%22%3A%22BebasNeueBold%22%2C%22family%22%3A%22Bebas%20Neue%22%2C%22style%22%3A%22Bold%22%7D%2C%22originalFont%22%3A%7B%22source%22%3A%22AF%22%2C%22id%22%3A%22TkD-37900-2fcb08c1acb10c553a809c1b259a7f5ebaa037cc%22%2C%22postscriptName%22%3A%22BebasNeueBold%22%2C%22family%22%3A%22Bebas%20Neue%22%2C%22style%22%3A%22Bold%22%7D%2C%22fontSize%22%3A75%2C%22color%22%3A%7B%22a%22%3A1%2C%22r%22%3A1%2C%22g%22%3A1%2C%22b%22%3A1%7D%2C%22strikethrough%22%3Afalse%2C%22tracking%22%3A0%2C%22underline%22%3Afalse%2C%22features%22%3A%5B%5D%2C%22textScript%22%3A0%7D%2C%22length%22%3A34%7D%5D%2C%22paragraphs%22%3A%5B%7B%22style%22%3A%7B%22leading%22%3A%7B%22amount%22%3A0.9599999785423279%2C%22type%22%3A1%7D%2C%22listStyle%22%3A%7B%22listId%22%3A%22%22%2C%22listLevel%22%3A0%7D%2C%22direction%22%3A0%2C%22spaceAfter%22%3A0%2C%22spaceBefore%22%3A0%2C%22assigned%22%3A15%7D%2C%22length%22%3A21%7D%2C%7B%22style%22%3A%7B%22leading%22%3A%7B%22amount%22%3A0.9599999785423279%2C%22type%22%3A1%7D%2C%22listStyle%22%3A%7B%22listId%22%3A%22%22%2C%22listLevel%22%3A0%7D%2C%22direction%22%3A0%2C%22spaceAfter%22%3A0%2C%22spaceBefore%22%3A0%2C%22assigned%22%3A15%7D%2C%22length%22%3A13%7D%5D%2C%22listStyles%22%3A%5B%5D%7D%2C%22objectStyle%22%3A%7B%22languageLayoutProfile%22%3A%7B%22name%22%3A%22langDefault%22%2C%22version%22%3A1%7D%7D%7D%2C%22TextDefaultValueChanged%22%3A%7B%7D%2C%22TextForwardReferencesMap%22%3A%7B%22entityIdMapping%22%3A%7B%7D%7D%2C%22ArtboardRelativeSceneNodeTransform%22%3A%7B%22x%22%3A333.0556640625%2C%22y%22%3A451.0825500488281%2C%22rotation%22%3A0%7D%2C%22CopyPastePixelInformation%22%3A%7B%22density%22%3A96%7D%7D%7D%2C%22version%22%3A360%2C%22draftDocumentModels%22%3A%22%22%7D%2C%22entityIds%22%3A%5B%22de50cee4-0ae2-4c31-8194-3c59572e4f45%22%5D%7D%2C%22metadata%22%3A%7B%22sourceContext%22%3A%222fefd5ce-7b39-489b-97cb-5c334191ef8e%22%7D%7D(\/Adobe)--&gt;\">Licenses valid until October 2026<\/span><\/h2>\n<p><span data-buffer=\"&lt;!--(Adobe)%7B%22type%22%3A%22horizonObject%22%2C%22payload%22%3A%7B%22docId%22%3A%22urn%3Aaaid%3Asc%3AUS%3A8681444c-8303-573a-b790-8847c2c7c635%22%2C%22repositoryId%22%3A%22urn%3Aaaid%3Asc%3AUS%3A7f347c18-c8a3-52e5-8bb6-5722e61eca28%22%2C%22copyClientId%22%3A%227e93896b-cf25-4627-a556-963a884a22fc%22%2C%22docModel%22%3A%7B%22isFullDocument%22%3Afalse%2C%22serializedECS%22%3A%7B%22AssetInfo%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22BitmapReference%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ForwardReference%22%3A%7B%7D%7D%2C%22BitmapRole%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22BlendMode%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22CanvasColor%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ContentCredentialsMetadata%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22LinkedAssetMetadata%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22EllipseGeometry%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22FillChildOf%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ChildOf%22%3A%7B%7D%7D%2C%22FillColor%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22IsColor%22%3A%7B%7D%7D%2C%22FillTransform%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22FillType%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ImageSaliencyMetadata%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22InvisibleBoundingBox%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22IsCropGroup%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22LineGeometry%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22MarkedForImport%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ObjectFit%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22PixelInformation%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22RectangleCornerRadii%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22RectangleGeometry%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceAvailability%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceHasCaiData%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceChildOf%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ChildOf%22%3A%7B%7D%7D%2C%22ResourceCollectionChildOf%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ChildOf%22%3A%7B%7D%2C%22WeakChildOf%22%3A%7B%7D%7D%2C%22ResourceCollectionInfo%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceCollectionOriginalContentHashSHA1%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceCollectionOriginalFileName%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceCollectionOriginalMimeType%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceCollectionOriginalResourceSize%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceDimensions%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceInfo%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceNeedsPublishing%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourcePreferredPixelFormat%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceUrl%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeAspectLock%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeChildOf%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ChildOf%22%3A%7B%7D%7D%2C%22SceneNodeLockCurrent%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22AffectsEditabilityTrait%22%3A%7B%7D%7D%2C%22SceneNodeLockMinimum%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeName%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeOpacity%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeTransform%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeType%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22slot%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeCap%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeChildOf%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ChildOf%22%3A%7B%7D%7D%2C%22StrokeColor%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22IsColor%22%3A%7B%7D%7D%2C%22StrokeDashGeometry%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeJoin%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeMiter%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokePosition%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeType%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeWidth%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SourceAssetIdentifier%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22TimingInfo%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22VisibleBoundingBox%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22XMPMetadata%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22BatchCreateDataMapping%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeAncestorLockState%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22AffectsEditabilityTrait%22%3A%7B%7D%7D%2C%22%23decoration%22%3A%7B%22NonPersistable%22%3A%7B%7D%7D%2C%22%23canvas%22%3A%7B%22NonPersistable%22%3A%7B%7D%7D%2C%22%23effects%22%3A%7B%22NonPersistable%22%3A%7B%7D%7D%2C%22ResourceIsUploading%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22PendingSave%22%3A%7B%7D%7D%2C%22ResourceCollectionIsStoringInIDB%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22PendingSave%22%3A%7B%7D%7D%2C%22e54720ab-2928-4657-9c1a-da6752a6af47%22%3A%7B%22SceneNodeTransform%22%3A%7B%22x%22%3A345.34375%2C%22y%22%3A828%2C%22rotation%22%3A0%2C%22scaleX%22%3A1.3333333333333333%2C%22scaleY%22%3A1.3333333333333333%7D%2C%22SceneNodeType%22%3A%7B%22type%22%3A%22Text%22%7D%2C%22TextType%22%3A%7B%22allowMultiframe%22%3Afalse%7D%2C%22TextAlignment%22%3A%7B%22alignment%22%3A1%7D%2C%22TextGeometry%22%3A%7B%22type%22%3A2%2C%22damaged%22%3Atrue%2C%22width%22%3A449.27008056640625%2C%22height%22%3A193.84373474121094%2C%22baselineOffset%22%3A0%7D%2C%22TextModel%22%3A%7B%22text%22%3A%22If%20your%20work%20permit%20or%20immigration%20document%20expires%20on%20October%202%2C%202026%2C%5Cu0003%5CrYour%20driver%E2%80%99s%20license%20will%20remain%20valid%20until%20that%20date.%22%2C%22styles%22%3A%7B%22ranges%22%3A%5B%7B%22charStyle%22%3A%7B%22assigned%22%3A493%2C%22font%22%3A%7B%22source%22%3A%22AF%22%2C%22id%22%3A%22TkD-37516-9d7b232dfcf705029e0147542746f012c505492a%22%2C%22postscriptName%22%3A%22Poppins-Regular%22%2C%22family%22%3A%22Poppins%22%2C%22style%22%3A%22Regular%22%7D%2C%22originalFont%22%3A%7B%22source%22%3A%22AF%22%2C%22id%22%3A%22TkD-37516-9d7b232dfcf705029e0147542746f012c505492a%22%2C%22postscriptName%22%3A%22Poppins-Regular%22%2C%22family%22%3A%22Poppins%22%2C%22style%22%3A%22Regular%22%7D%2C%22fontSize%22%3A28.936260223388672%2C%22color%22%3A%7B%22a%22%3A1%2C%22r%22%3A1%2C%22g%22%3A1%2C%22b%22%3A1%7D%2C%22strikethrough%22%3Afalse%2C%22tracking%22%3A0%2C%22underline%22%3Afalse%2C%22features%22%3A%5B%5D%2C%22textScript%22%3A0%7D%2C%22length%22%3A73%7D%2C%7B%22charStyle%22%3A%7B%22assigned%22%3A493%2C%22font%22%3A%7B%22source%22%3A%22AF%22%2C%22id%22%3A%22TkD-37522-081c553765c22d6faa6be97224780b959552406a%22%2C%22postscriptName%22%3A%22Poppins-Bold%22%2C%22family%22%3A%22Poppins%22%2C%22style%22%3A%22Bold%22%7D%2C%22originalFont%22%3A%7B%22source%22%3A%22AF%22%2C%22id%22%3A%22TkD-37522-081c553765c22d6faa6be97224780b959552406a%22%2C%22postscriptName%22%3A%22Poppins-Bold%22%2C%22family%22%3A%22Poppins%22%2C%22style%22%3A%22Bold%22%7D%2C%22fontSize%22%3A28.936260223388672%2C%22color%22%3A%7B%22a%22%3A1%2C%22r%22%3A1%2C%22g%22%3A1%2C%22b%22%3A1%7D%2C%22strikethrough%22%3Afalse%2C%22tracking%22%3A0%2C%22underline%22%3Afalse%2C%22features%22%3A%5B%5D%2C%22textScript%22%3A0%7D%2C%22length%22%3A56%7D%5D%2C%22paragraphs%22%3A%5B%7B%22style%22%3A%7B%22leading%22%3A%7B%22amount%22%3A1.100000023841858%2C%22type%22%3A1%7D%2C%22listStyle%22%3A%7B%22listId%22%3A%22%22%2C%22listLevel%22%3A0%7D%2C%22direction%22%3A0%2C%22spaceAfter%22%3A0%2C%22spaceBefore%22%3A0%2C%22assigned%22%3A15%7D%2C%22length%22%3A72%7D%2C%7B%22style%22%3A%7B%22leading%22%3A%7B%22amount%22%3A1.100000023841858%2C%22type%22%3A1%7D%2C%22listStyle%22%3A%7B%22listId%22%3A%22%22%2C%22listLevel%22%3A0%7D%2C%22direction%22%3A0%2C%22spaceAfter%22%3A0%2C%22spaceBefore%22%3A0%2C%22assigned%22%3A15%7D%2C%22length%22%3A1%7D%2C%7B%22style%22%3A%7B%22leading%22%3A%7B%22amount%22%3A1.100000023841858%2C%22type%22%3A1%7D%2C%22listStyle%22%3A%7B%22listId%22%3A%22%22%2C%22listLevel%22%3A0%7D%2C%22direction%22%3A0%2C%22spaceAfter%22%3A0%2C%22spaceBefore%22%3A0%2C%22assigned%22%3A15%7D%2C%22length%22%3A56%7D%5D%2C%22listStyles%22%3A%5B%5D%7D%2C%22objectStyle%22%3A%7B%22languageLayoutProfile%22%3A%7B%22name%22%3A%22langDefault%22%2C%22version%22%3A1%7D%7D%7D%2C%22TextDefaultValueChanged%22%3A%7B%7D%2C%22TextForwardReferencesMap%22%3A%7B%22entityIdMapping%22%3A%7B%7D%7D%2C%22ArtboardRelativeSceneNodeTransform%22%3A%7B%22x%22%3A345.34375%2C%22y%22%3A828%2C%22rotation%22%3A0%7D%2C%22CopyPastePixelInformation%22%3A%7B%22density%22%3A96%7D%7D%7D%2C%22version%22%3A360%2C%22draftDocumentModels%22%3A%22%22%7D%2C%22entityIds%22%3A%5B%22e54720ab-2928-4657-9c1a-da6752a6af47%22%5D%7D%2C%22metadata%22%3A%7B%22sourceContext%22%3A%222fefd5ce-7b39-489b-97cb-5c334191ef8e%22%7D%7D(\/Adobe)--&gt;\">If your work permit or immigration document expires on October 2, 2026,\u0003 Your driver\u2019s license will remain valid until that date.<\/span><\/p>\n<h2><span data-buffer=\"&lt;!--(Adobe)%7B%22type%22%3A%22horizonObject%22%2C%22payload%22%3A%7B%22docId%22%3A%22urn%3Aaaid%3Asc%3AUS%3A8681444c-8303-573a-b790-8847c2c7c635%22%2C%22repositoryId%22%3A%22urn%3Aaaid%3Asc%3AUS%3A7f347c18-c8a3-52e5-8bb6-5722e61eca28%22%2C%22copyClientId%22%3A%227e93896b-cf25-4627-a556-963a884a22fc%22%2C%22docModel%22%3A%7B%22isFullDocument%22%3Afalse%2C%22serializedECS%22%3A%7B%22AssetInfo%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22BitmapReference%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ForwardReference%22%3A%7B%7D%7D%2C%22BitmapRole%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22BlendMode%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22CanvasColor%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ContentCredentialsMetadata%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22LinkedAssetMetadata%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22EllipseGeometry%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22FillChildOf%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ChildOf%22%3A%7B%7D%7D%2C%22FillColor%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22IsColor%22%3A%7B%7D%7D%2C%22FillTransform%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22FillType%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ImageSaliencyMetadata%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22InvisibleBoundingBox%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22IsCropGroup%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22LineGeometry%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22MarkedForImport%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ObjectFit%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22PixelInformation%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22RectangleCornerRadii%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22RectangleGeometry%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceAvailability%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceHasCaiData%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceChildOf%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ChildOf%22%3A%7B%7D%7D%2C%22ResourceCollectionChildOf%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ChildOf%22%3A%7B%7D%2C%22WeakChildOf%22%3A%7B%7D%7D%2C%22ResourceCollectionInfo%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceCollectionOriginalContentHashSHA1%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceCollectionOriginalFileName%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceCollectionOriginalMimeType%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceCollectionOriginalResourceSize%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceDimensions%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceInfo%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceNeedsPublishing%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourcePreferredPixelFormat%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceUrl%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeAspectLock%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeChildOf%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ChildOf%22%3A%7B%7D%7D%2C%22SceneNodeLockCurrent%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22AffectsEditabilityTrait%22%3A%7B%7D%7D%2C%22SceneNodeLockMinimum%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeName%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeOpacity%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeTransform%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeType%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22slot%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeCap%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeChildOf%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ChildOf%22%3A%7B%7D%7D%2C%22StrokeColor%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22IsColor%22%3A%7B%7D%7D%2C%22StrokeDashGeometry%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeJoin%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeMiter%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokePosition%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeType%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeWidth%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SourceAssetIdentifier%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22TimingInfo%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22VisibleBoundingBox%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22XMPMetadata%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22BatchCreateDataMapping%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeAncestorLockState%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22AffectsEditabilityTrait%22%3A%7B%7D%7D%2C%22%23decoration%22%3A%7B%22NonPersistable%22%3A%7B%7D%7D%2C%22%23canvas%22%3A%7B%22NonPersistable%22%3A%7B%7D%7D%2C%22%23effects%22%3A%7B%22NonPersistable%22%3A%7B%7D%7D%2C%22ResourceIsUploading%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22PendingSave%22%3A%7B%7D%7D%2C%22ResourceCollectionIsStoringInIDB%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22PendingSave%22%3A%7B%7D%7D%2C%2290582064-06b8-4c7e-bb5b-9d9ee0dccdb2%22%3A%7B%22SceneNodeTransform%22%3A%7B%22x%22%3A124.033203125%2C%22y%22%3A300.52197265625%2C%22rotation%22%3A0%2C%22scaleX%22%3A1.3333333333333333%2C%22scaleY%22%3A1.3333333333333333%7D%2C%22SceneNodeType%22%3A%7B%22type%22%3A%22Text%22%7D%2C%22TextType%22%3A%7B%22allowMultiframe%22%3Afalse%7D%2C%22TextAlignment%22%3A%7B%22alignment%22%3A1%7D%2C%22TextGeometry%22%3A%7B%22type%22%3A2%2C%22damaged%22%3Atrue%2C%22width%22%3A374.21136474609375%2C%22height%22%3A212.9993133544922%2C%22baselineOffset%22%3A0%7D%2C%22TextModel%22%3A%7B%22text%22%3A%22Licenses%20valid%20through%5CrApril%202026%22%2C%22styles%22%3A%7B%22ranges%22%3A%5B%7B%22charStyle%22%3A%7B%22assigned%22%3A493%2C%22font%22%3A%7B%22source%22%3A%22AF%22%2C%22id%22%3A%22TkD-37900-2fcb08c1acb10c553a809c1b259a7f5ebaa037cc%22%2C%22postscriptName%22%3A%22BebasNeueBold%22%2C%22family%22%3A%22Bebas%20Neue%22%2C%22style%22%3A%22Bold%22%7D%2C%22originalFont%22%3A%7B%22source%22%3A%22AF%22%2C%22id%22%3A%22TkD-37900-2fcb08c1acb10c553a809c1b259a7f5ebaa037cc%22%2C%22postscriptName%22%3A%22BebasNeueBold%22%2C%22family%22%3A%22Bebas%20Neue%22%2C%22style%22%3A%22Bold%22%7D%2C%22fontSize%22%3A75%2C%22color%22%3A%7B%22a%22%3A1%2C%22r%22%3A1%2C%22g%22%3A1%2C%22b%22%3A1%7D%2C%22strikethrough%22%3Afalse%2C%22tracking%22%3A0%2C%22underline%22%3Afalse%2C%22features%22%3A%5B%5D%2C%22textScript%22%3A0%7D%2C%22length%22%3A33%7D%5D%2C%22paragraphs%22%3A%5B%7B%22style%22%3A%7B%22leading%22%3A%7B%22amount%22%3A0.8700000047683716%2C%22type%22%3A1%7D%2C%22listStyle%22%3A%7B%22listId%22%3A%22%22%2C%22listLevel%22%3A0%7D%2C%22direction%22%3A0%2C%22spaceAfter%22%3A0%2C%22spaceBefore%22%3A0%2C%22assigned%22%3A15%7D%2C%22length%22%3A23%7D%2C%7B%22style%22%3A%7B%22leading%22%3A%7B%22amount%22%3A0.8700000047683716%2C%22type%22%3A1%7D%2C%22listStyle%22%3A%7B%22listId%22%3A%22%22%2C%22listLevel%22%3A0%7D%2C%22direction%22%3A0%2C%22spaceAfter%22%3A0%2C%22spaceBefore%22%3A0%2C%22assigned%22%3A15%7D%2C%22length%22%3A10%7D%5D%2C%22listStyles%22%3A%5B%5D%7D%2C%22objectStyle%22%3A%7B%22languageLayoutProfile%22%3A%7B%22name%22%3A%22langDefault%22%2C%22version%22%3A1%7D%7D%7D%2C%22TextDefaultValueChanged%22%3A%7B%7D%2C%22TextForwardReferencesMap%22%3A%7B%22entityIdMapping%22%3A%7B%7D%7D%2C%22ArtboardRelativeSceneNodeTransform%22%3A%7B%22x%22%3A124.033203125%2C%22y%22%3A300.52197265625%2C%22rotation%22%3A0%7D%2C%22CopyPastePixelInformation%22%3A%7B%22density%22%3A96%7D%7D%7D%2C%22version%22%3A360%2C%22draftDocumentModels%22%3A%22%22%7D%2C%22entityIds%22%3A%5B%2290582064-06b8-4c7e-bb5b-9d9ee0dccdb2%22%5D%7D%2C%22metadata%22%3A%7B%22sourceContext%22%3A%22258ab13f-6ffd-4916-8ce7-c545565c2eef%22%7D%7D(\/Adobe)--&gt;\">Licenses valid through April 2026<\/span><\/h2>\n<p><span data-buffer=\"&lt;!--(Adobe)%7B%22type%22%3A%22horizonObject%22%2C%22payload%22%3A%7B%22docId%22%3A%22urn%3Aaaid%3Asc%3AUS%3A8681444c-8303-573a-b790-8847c2c7c635%22%2C%22repositoryId%22%3A%22urn%3Aaaid%3Asc%3AUS%3A7f347c18-c8a3-52e5-8bb6-5722e61eca28%22%2C%22copyClientId%22%3A%227e93896b-cf25-4627-a556-963a884a22fc%22%2C%22docModel%22%3A%7B%22isFullDocument%22%3Afalse%2C%22serializedECS%22%3A%7B%22AssetInfo%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22BitmapReference%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ForwardReference%22%3A%7B%7D%7D%2C%22BitmapRole%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22BlendMode%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22CanvasColor%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ContentCredentialsMetadata%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22LinkedAssetMetadata%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22EllipseGeometry%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22FillChildOf%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ChildOf%22%3A%7B%7D%7D%2C%22FillColor%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22IsColor%22%3A%7B%7D%7D%2C%22FillTransform%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22FillType%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ImageSaliencyMetadata%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22InvisibleBoundingBox%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22IsCropGroup%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22LineGeometry%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22MarkedForImport%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ObjectFit%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22PixelInformation%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22RectangleCornerRadii%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22RectangleGeometry%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceAvailability%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceHasCaiData%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceChildOf%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ChildOf%22%3A%7B%7D%7D%2C%22ResourceCollectionChildOf%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ChildOf%22%3A%7B%7D%2C%22WeakChildOf%22%3A%7B%7D%7D%2C%22ResourceCollectionInfo%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceCollectionOriginalContentHashSHA1%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceCollectionOriginalFileName%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceCollectionOriginalMimeType%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceCollectionOriginalResourceSize%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceDimensions%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceInfo%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceNeedsPublishing%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourcePreferredPixelFormat%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceUrl%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeAspectLock%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeChildOf%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ChildOf%22%3A%7B%7D%7D%2C%22SceneNodeLockCurrent%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22AffectsEditabilityTrait%22%3A%7B%7D%7D%2C%22SceneNodeLockMinimum%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeName%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeOpacity%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeTransform%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeType%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22slot%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeCap%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeChildOf%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ChildOf%22%3A%7B%7D%7D%2C%22StrokeColor%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22IsColor%22%3A%7B%7D%7D%2C%22StrokeDashGeometry%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeJoin%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeMiter%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokePosition%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeType%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeWidth%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SourceAssetIdentifier%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22TimingInfo%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22VisibleBoundingBox%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22XMPMetadata%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22BatchCreateDataMapping%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeAncestorLockState%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22AffectsEditabilityTrait%22%3A%7B%7D%7D%2C%22%23decoration%22%3A%7B%22NonPersistable%22%3A%7B%7D%7D%2C%22%23canvas%22%3A%7B%22NonPersistable%22%3A%7B%7D%7D%2C%22%23effects%22%3A%7B%22NonPersistable%22%3A%7B%7D%7D%2C%22ResourceIsUploading%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22PendingSave%22%3A%7B%7D%7D%2C%22ResourceCollectionIsStoringInIDB%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22PendingSave%22%3A%7B%7D%7D%2C%22b663cf44-db1d-4fec-b0bd-c8499ee7a4b9%22%3A%7B%22SceneNodeTransform%22%3A%7B%22x%22%3A124.033203125%2C%22y%22%3A631.3801100254059%2C%22rotation%22%3A0%2C%22scaleX%22%3A1.3333333333333333%2C%22scaleY%22%3A1.3333333333333333%7D%2C%22SceneNodeType%22%3A%7B%22type%22%3A%22Text%22%7D%2C%22TextType%22%3A%7B%22allowMultiframe%22%3Afalse%7D%2C%22TextAlignment%22%3A%7B%22alignment%22%3A1%7D%2C%22TextGeometry%22%3A%7B%22type%22%3A2%2C%22damaged%22%3Atrue%2C%22width%22%3A529.593994140625%2C%22height%22%3A347.970703125%2C%22baselineOffset%22%3A0%7D%2C%22TextModel%22%3A%7B%22text%22%3A%22If%20your%20document%20lists%20any%20of%20these%20dates%3A%5Cr%5CrSeptember%209%2C%202022.%5CrMarch%2010%2C%202024.%5CrApril%202%2C%202025.%5CrSeptember%2010%2C%202025.%5Cr%5CrYour%20license%20will%20remain%20valid%20until%5CrApril%202%2C%202026.%22%2C%22styles%22%3A%7B%22ranges%22%3A%5B%7B%22charStyle%22%3A%7B%22assigned%22%3A493%2C%22font%22%3A%7B%22source%22%3A%22AF%22%2C%22id%22%3A%22TkD-37516-9d7b232dfcf705029e0147542746f012c505492a%22%2C%22postscriptName%22%3A%22Poppins-Regular%22%2C%22family%22%3A%22Poppins%22%2C%22style%22%3A%22Regular%22%7D%2C%22originalFont%22%3A%7B%22source%22%3A%22AF%22%2C%22id%22%3A%22TkD-37516-9d7b232dfcf705029e0147542746f012c505492a%22%2C%22postscriptName%22%3A%22Poppins-Regular%22%2C%22family%22%3A%22Poppins%22%2C%22style%22%3A%22Regular%22%7D%2C%22fontSize%22%3A29%2C%22color%22%3A%7B%22a%22%3A1%2C%22r%22%3A1%2C%22g%22%3A1%2C%22b%22%3A1%7D%2C%22strikethrough%22%3Afalse%2C%22tracking%22%3A0%2C%22underline%22%3Afalse%2C%22features%22%3A%5B%5D%2C%22textScript%22%3A0%7D%2C%22length%22%3A115%7D%2C%7B%22charStyle%22%3A%7B%22assigned%22%3A495%2C%22font%22%3A%7B%22source%22%3A%22AF%22%2C%22id%22%3A%22TkD-37522-081c553765c22d6faa6be97224780b959552406a%22%2C%22postscriptName%22%3A%22Poppins-Bold%22%2C%22family%22%3A%22Poppins%22%2C%22style%22%3A%22Bold%22%7D%2C%22originalFont%22%3A%7B%22source%22%3A%22AF%22%2C%22id%22%3A%22TkD-37522-081c553765c22d6faa6be97224780b959552406a%22%2C%22postscriptName%22%3A%22Poppins-Bold%22%2C%22family%22%3A%22Poppins%22%2C%22style%22%3A%22Bold%22%7D%2C%22fontSize%22%3A29%2C%22color%22%3A%7B%22a%22%3A1%2C%22r%22%3A1%2C%22g%22%3A1%2C%22b%22%3A1%7D%2C%22strikethrough%22%3Afalse%2C%22tracking%22%3A0%2C%22underline%22%3Afalse%2C%22features%22%3A%5B%5D%2C%22textScript%22%3A0%7D%2C%22length%22%3A51%7D%5D%2C%22paragraphs%22%3A%5B%7B%22style%22%3A%7B%22leading%22%3A%7B%22amount%22%3A1.2000000476837158%2C%22type%22%3A1%7D%2C%22listStyle%22%3A%7B%22listId%22%3A%22%22%2C%22listLevel%22%3A0%7D%2C%22direction%22%3A0%2C%22spaceAfter%22%3A0%2C%22spaceBefore%22%3A0%2C%22assigned%22%3A15%7D%2C%22length%22%3A43%7D%2C%7B%22style%22%3A%7B%22leading%22%3A%7B%22amount%22%3A1.2000000476837158%2C%22type%22%3A1%7D%2C%22listStyle%22%3A%7B%22listId%22%3A%22%22%2C%22listLevel%22%3A0%7D%2C%22direction%22%3A0%2C%22spaceAfter%22%3A0%2C%22spaceBefore%22%3A0%2C%22assigned%22%3A15%7D%2C%22length%22%3A1%7D%2C%7B%22style%22%3A%7B%22leading%22%3A%7B%22amount%22%3A1.2000000476837158%2C%22type%22%3A1%7D%2C%22listStyle%22%3A%7B%22listId%22%3A%221f0e96ca-a672-48a1-a299-1b8f5127dc49%22%2C%22listLevel%22%3A0%7D%2C%22direction%22%3A0%2C%22spaceAfter%22%3A0%2C%22spaceBefore%22%3A0%2C%22assigned%22%3A15%7D%2C%22length%22%3A19%7D%2C%7B%22style%22%3A%7B%22leading%22%3A%7B%22amount%22%3A1.2000000476837158%2C%22type%22%3A1%7D%2C%22listStyle%22%3A%7B%22listId%22%3A%221f0e96ca-a672-48a1-a299-1b8f5127dc49%22%2C%22listLevel%22%3A0%7D%2C%22direction%22%3A0%2C%22spaceAfter%22%3A0%2C%22spaceBefore%22%3A0%2C%22assigned%22%3A15%7D%2C%22length%22%3A16%7D%2C%7B%22style%22%3A%7B%22leading%22%3A%7B%22amount%22%3A1.2000000476837158%2C%22type%22%3A1%7D%2C%22listStyle%22%3A%7B%22listId%22%3A%221f0e96ca-a672-48a1-a299-1b8f5127dc49%22%2C%22listLevel%22%3A0%7D%2C%22direction%22%3A0%2C%22spaceAfter%22%3A0%2C%22spaceBefore%22%3A0%2C%22assigned%22%3A15%7D%2C%22length%22%3A15%7D%2C%7B%22style%22%3A%7B%22leading%22%3A%7B%22amount%22%3A1.2000000476837158%2C%22type%22%3A1%7D%2C%22listStyle%22%3A%7B%22listId%22%3A%221f0e96ca-a672-48a1-a299-1b8f5127dc49%22%2C%22listLevel%22%3A0%7D%2C%22direction%22%3A0%2C%22spaceAfter%22%3A0%2C%22spaceBefore%22%3A0%2C%22assigned%22%3A15%7D%2C%22length%22%3A20%7D%2C%7B%22style%22%3A%7B%22leading%22%3A%7B%22amount%22%3A1.2000000476837158%2C%22type%22%3A1%7D%2C%22listStyle%22%3A%7B%22listId%22%3A%22%22%2C%22listLevel%22%3A0%7D%2C%22direction%22%3A0%2C%22spaceAfter%22%3A0%2C%22spaceBefore%22%3A0%2C%22assigned%22%3A15%7D%2C%22length%22%3A1%7D%2C%7B%22style%22%3A%7B%22leading%22%3A%7B%22amount%22%3A1.2000000476837158%2C%22type%22%3A1%7D%2C%22listStyle%22%3A%7B%22listId%22%3A%22%22%2C%22listLevel%22%3A0%7D%2C%22direction%22%3A0%2C%22spaceAfter%22%3A0%2C%22spaceBefore%22%3A0%2C%22assigned%22%3A15%7D%2C%22length%22%3A37%7D%2C%7B%22style%22%3A%7B%22leading%22%3A%7B%22amount%22%3A1.2000000476837158%2C%22type%22%3A1%7D%2C%22listStyle%22%3A%7B%22listId%22%3A%22%22%2C%22listLevel%22%3A0%7D%2C%22direction%22%3A0%2C%22spaceAfter%22%3A0%2C%22spaceBefore%22%3A0%2C%22assigned%22%3A15%7D%2C%22length%22%3A14%7D%5D%2C%22listStyles%22%3A%5B%7B%22id%22%3A%221f0e96ca-a672-48a1-a299-1b8f5127dc49%22%2C%22levels%22%3A%5B%7B%22prefix%22%3A%22%22%2C%22postfix%22%3A%22%22%2C%22bullet%22%3A%22%E2%80%A2%22%2C%22generator%22%3A6%7D%2C%7B%22prefix%22%3A%22%22%2C%22postfix%22%3A%22%22%2C%22bullet%22%3A%22%E2%97%A6%22%2C%22generator%22%3A6%7D%2C%7B%22prefix%22%3A%22%22%2C%22postfix%22%3A%22%22%2C%22bullet%22%3A%22%E2%96%AA%22%2C%22generator%22%3A6%7D%2C%7B%22prefix%22%3A%22%22%2C%22postfix%22%3A%22%22%2C%22bullet%22%3A%22%E2%96%AB%22%2C%22generator%22%3A6%7D%2C%7B%22prefix%22%3A%22%22%2C%22postfix%22%3A%22%22%2C%22bullet%22%3A%22%E2%80%A2%22%2C%22generator%22%3A6%7D%2C%7B%22prefix%22%3A%22%22%2C%22postfix%22%3A%22%22%2C%22bullet%22%3A%22%E2%97%A6%22%2C%22generator%22%3A6%7D%2C%7B%22prefix%22%3A%22%22%2C%22postfix%22%3A%22%22%2C%22bullet%22%3A%22%E2%96%AA%22%2C%22generator%22%3A6%7D%2C%7B%22prefix%22%3A%22%22%2C%22postfix%22%3A%22%22%2C%22bullet%22%3A%22%E2%96%AB%22%2C%22generator%22%3A6%7D%2C%7B%22prefix%22%3A%22%22%2C%22postfix%22%3A%22%22%2C%22bullet%22%3A%22%E2%80%A2%22%2C%22generator%22%3A6%7D%2C%7B%22prefix%22%3A%22%22%2C%22postfix%22%3A%22%22%2C%22bullet%22%3A%22%E2%97%A6%22%2C%22generator%22%3A6%7D%2C%7B%22prefix%22%3A%22%22%2C%22postfix%22%3A%22%22%2C%22bullet%22%3A%22%E2%96%AA%22%2C%22generator%22%3A6%7D%2C%7B%22prefix%22%3A%22%22%2C%22postfix%22%3A%22%22%2C%22bullet%22%3A%22%E2%96%AB%22%2C%22generator%22%3A6%7D%5D%7D%5D%7D%2C%22objectStyle%22%3A%7B%22languageLayoutProfile%22%3A%7B%22name%22%3A%22langDefault%22%2C%22version%22%3A1%7D%7D%7D%2C%22TextDefaultValueChanged%22%3A%7B%7D%2C%22TextForwardReferencesMap%22%3A%7B%22entityIdMapping%22%3A%7B%7D%7D%2C%22ArtboardRelativeSceneNodeTransform%22%3A%7B%22x%22%3A124.033203125%2C%22y%22%3A631.380126953125%2C%22rotation%22%3A0%7D%2C%22CopyPastePixelInformation%22%3A%7B%22density%22%3A96%7D%7D%7D%2C%22version%22%3A360%2C%22draftDocumentModels%22%3A%22%22%7D%2C%22entityIds%22%3A%5B%22b663cf44-db1d-4fec-b0bd-c8499ee7a4b9%22%5D%7D%2C%22metadata%22%3A%7B%22sourceContext%22%3A%22258ab13f-6ffd-4916-8ce7-c545565c2eef%22%7D%7D(\/Adobe)--&gt;\">If your document lists any of these dates: September 9, 2022. March 10, 2024. April 2, 2025. September 10, 2025. Your license will remain valid until April 2, 2026.<\/span><\/p>\n<h2><span data-buffer=\"&lt;!--(Adobe)%7B%22type%22%3A%22horizonObject%22%2C%22payload%22%3A%7B%22docId%22%3A%22urn%3Aaaid%3Asc%3AUS%3A8681444c-8303-573a-b790-8847c2c7c635%22%2C%22repositoryId%22%3A%22urn%3Aaaid%3Asc%3AUS%3A7f347c18-c8a3-52e5-8bb6-5722e61eca28%22%2C%22copyClientId%22%3A%227e93896b-cf25-4627-a556-963a884a22fc%22%2C%22docModel%22%3A%7B%22isFullDocument%22%3Afalse%2C%22serializedECS%22%3A%7B%22AssetInfo%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22BitmapReference%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ForwardReference%22%3A%7B%7D%7D%2C%22BitmapRole%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22BlendMode%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22CanvasColor%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ContentCredentialsMetadata%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22LinkedAssetMetadata%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22EllipseGeometry%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22FillChildOf%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ChildOf%22%3A%7B%7D%7D%2C%22FillColor%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22IsColor%22%3A%7B%7D%7D%2C%22FillTransform%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22FillType%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ImageSaliencyMetadata%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22InvisibleBoundingBox%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22IsCropGroup%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22LineGeometry%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22MarkedForImport%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ObjectFit%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22PixelInformation%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22RectangleCornerRadii%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22RectangleGeometry%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceAvailability%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceHasCaiData%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceChildOf%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ChildOf%22%3A%7B%7D%7D%2C%22ResourceCollectionChildOf%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ChildOf%22%3A%7B%7D%2C%22WeakChildOf%22%3A%7B%7D%7D%2C%22ResourceCollectionInfo%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceCollectionOriginalContentHashSHA1%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceCollectionOriginalFileName%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceCollectionOriginalMimeType%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceCollectionOriginalResourceSize%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceDimensions%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceInfo%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceNeedsPublishing%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourcePreferredPixelFormat%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceUrl%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeAspectLock%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeChildOf%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ChildOf%22%3A%7B%7D%7D%2C%22SceneNodeLockCurrent%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22AffectsEditabilityTrait%22%3A%7B%7D%7D%2C%22SceneNodeLockMinimum%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeName%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeOpacity%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeTransform%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeType%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22slot%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeCap%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeChildOf%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ChildOf%22%3A%7B%7D%7D%2C%22StrokeColor%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22IsColor%22%3A%7B%7D%7D%2C%22StrokeDashGeometry%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeJoin%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeMiter%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokePosition%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeType%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeWidth%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SourceAssetIdentifier%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22TimingInfo%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22VisibleBoundingBox%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22XMPMetadata%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22BatchCreateDataMapping%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeAncestorLockState%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22AffectsEditabilityTrait%22%3A%7B%7D%7D%2C%22%23decoration%22%3A%7B%22NonPersistable%22%3A%7B%7D%7D%2C%22%23canvas%22%3A%7B%22NonPersistable%22%3A%7B%7D%7D%2C%22%23effects%22%3A%7B%22NonPersistable%22%3A%7B%7D%7D%2C%22ResourceIsUploading%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22PendingSave%22%3A%7B%7D%7D%2C%22ResourceCollectionIsStoringInIDB%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22PendingSave%22%3A%7B%7D%7D%2C%2230a3cf52-3680-43b8-8bbc-b2dffe0657a7%22%3A%7B%22SceneNodeTransform%22%3A%7B%22x%22%3A123.47265625%2C%22y%22%3A370.12137055397034%2C%22rotation%22%3A0%2C%22scaleX%22%3A1.3333333333333333%2C%22scaleY%22%3A1.3333333333333333%7D%2C%22SceneNodeType%22%3A%7B%22type%22%3A%22Text%22%7D%2C%22TextType%22%3A%7B%22allowMultiframe%22%3Afalse%7D%2C%22TextAlignment%22%3A%7B%22alignment%22%3A1%7D%2C%22TextGeometry%22%3A%7B%22type%22%3A2%2C%22damaged%22%3Atrue%2C%22width%22%3A476.4207763671875%2C%22height%22%3A147.95953369140625%2C%22baselineOffset%22%3A0%7D%2C%22TextModel%22%3A%7B%22text%22%3A%22Check%20Your%20Documents%22%2C%22styles%22%3A%7B%22ranges%22%3A%5B%7B%22charStyle%22%3A%7B%22assigned%22%3A493%2C%22font%22%3A%7B%22source%22%3A%22AF%22%2C%22id%22%3A%22TkD-37900-2fcb08c1acb10c553a809c1b259a7f5ebaa037cc%22%2C%22postscriptName%22%3A%22BebasNeueBold%22%2C%22family%22%3A%22Bebas%20Neue%22%2C%22style%22%3A%22Bold%22%7D%2C%22originalFont%22%3A%7B%22source%22%3A%22AF%22%2C%22id%22%3A%22TkD-37900-2fcb08c1acb10c553a809c1b259a7f5ebaa037cc%22%2C%22postscriptName%22%3A%22BebasNeueBold%22%2C%22family%22%3A%22Bebas%20Neue%22%2C%22style%22%3A%22Bold%22%7D%2C%22fontSize%22%3A75.1067123413086%2C%22color%22%3A%7B%22a%22%3A1%2C%22r%22%3A1%2C%22g%22%3A1%2C%22b%22%3A1%7D%2C%22strikethrough%22%3Afalse%2C%22tracking%22%3A0%2C%22underline%22%3Afalse%2C%22features%22%3A%5B%5D%2C%22textScript%22%3A0%7D%2C%22length%22%3A20%7D%5D%2C%22paragraphs%22%3A%5B%7B%22style%22%3A%7B%22leading%22%3A%7B%22amount%22%3A0.8700000047683716%2C%22type%22%3A1%7D%2C%22listStyle%22%3A%7B%22listId%22%3A%22%22%2C%22listLevel%22%3A0%7D%2C%22direction%22%3A0%2C%22spaceAfter%22%3A0%2C%22spaceBefore%22%3A0%2C%22assigned%22%3A15%7D%2C%22length%22%3A20%7D%5D%2C%22listStyles%22%3A%5B%5D%7D%2C%22objectStyle%22%3A%7B%22languageLayoutProfile%22%3A%7B%22name%22%3A%22langDefault%22%2C%22version%22%3A1%7D%7D%7D%2C%22TextDefaultValueChanged%22%3A%7B%7D%2C%22TextForwardReferencesMap%22%3A%7B%22entityIdMapping%22%3A%7B%7D%7D%2C%22ArtboardRelativeSceneNodeTransform%22%3A%7B%22x%22%3A123.47265625%2C%22y%22%3A370.1213684082031%2C%22rotation%22%3A0%7D%2C%22CopyPastePixelInformation%22%3A%7B%22density%22%3A96%7D%7D%7D%2C%22version%22%3A360%2C%22draftDocumentModels%22%3A%22%22%7D%2C%22entityIds%22%3A%5B%2230a3cf52-3680-43b8-8bbc-b2dffe0657a7%22%5D%7D%2C%22metadata%22%3A%7B%22sourceContext%22%3A%229e247c53-8fcb-486b-8e63-c29a2361ec67%22%7D%7D(\/Adobe)--&gt;\">Check Your Documents<\/span><\/h2>\n<p><span data-buffer=\"&lt;!--(Adobe)%7B%22type%22%3A%22horizonObject%22%2C%22payload%22%3A%7B%22docId%22%3A%22urn%3Aaaid%3Asc%3AUS%3A8681444c-8303-573a-b790-8847c2c7c635%22%2C%22repositoryId%22%3A%22urn%3Aaaid%3Asc%3AUS%3A7f347c18-c8a3-52e5-8bb6-5722e61eca28%22%2C%22copyClientId%22%3A%227e93896b-cf25-4627-a556-963a884a22fc%22%2C%22docModel%22%3A%7B%22isFullDocument%22%3Afalse%2C%22serializedECS%22%3A%7B%22AssetInfo%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22BitmapReference%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ForwardReference%22%3A%7B%7D%7D%2C%22BitmapRole%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22BlendMode%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22CanvasColor%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ContentCredentialsMetadata%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22LinkedAssetMetadata%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22EllipseGeometry%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22FillChildOf%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ChildOf%22%3A%7B%7D%7D%2C%22FillColor%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22IsColor%22%3A%7B%7D%7D%2C%22FillTransform%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22FillType%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ImageSaliencyMetadata%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22InvisibleBoundingBox%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22IsCropGroup%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22LineGeometry%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22MarkedForImport%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ObjectFit%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22PixelInformation%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22RectangleCornerRadii%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22RectangleGeometry%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceAvailability%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceHasCaiData%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceChildOf%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ChildOf%22%3A%7B%7D%7D%2C%22ResourceCollectionChildOf%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ChildOf%22%3A%7B%7D%2C%22WeakChildOf%22%3A%7B%7D%7D%2C%22ResourceCollectionInfo%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceCollectionOriginalContentHashSHA1%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceCollectionOriginalFileName%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceCollectionOriginalMimeType%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceCollectionOriginalResourceSize%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceDimensions%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceInfo%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceNeedsPublishing%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourcePreferredPixelFormat%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceUrl%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeAspectLock%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeChildOf%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ChildOf%22%3A%7B%7D%7D%2C%22SceneNodeLockCurrent%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22AffectsEditabilityTrait%22%3A%7B%7D%7D%2C%22SceneNodeLockMinimum%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeName%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeOpacity%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeTransform%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeType%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22slot%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeCap%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeChildOf%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ChildOf%22%3A%7B%7D%7D%2C%22StrokeColor%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22IsColor%22%3A%7B%7D%7D%2C%22StrokeDashGeometry%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeJoin%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeMiter%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokePosition%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeType%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeWidth%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SourceAssetIdentifier%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22TimingInfo%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22VisibleBoundingBox%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22XMPMetadata%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22BatchCreateDataMapping%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeAncestorLockState%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22AffectsEditabilityTrait%22%3A%7B%7D%7D%2C%22%23decoration%22%3A%7B%22NonPersistable%22%3A%7B%7D%7D%2C%22%23canvas%22%3A%7B%22NonPersistable%22%3A%7B%7D%7D%2C%22%23effects%22%3A%7B%22NonPersistable%22%3A%7B%7D%7D%2C%22ResourceIsUploading%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22PendingSave%22%3A%7B%7D%7D%2C%22ResourceCollectionIsStoringInIDB%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22PendingSave%22%3A%7B%7D%7D%2C%22d0f907c6-2b53-40aa-bc2b-39ab00115b50%22%3A%7B%22SceneNodeTransform%22%3A%7B%22x%22%3A123.47265625%2C%22y%22%3A621.4978637695312%2C%22rotation%22%3A0%2C%22scaleX%22%3A1.3333333333333333%2C%22scaleY%22%3A1.3333333333333333%7D%2C%22SceneNodeType%22%3A%7B%22type%22%3A%22Text%22%7D%2C%22TextType%22%3A%7B%22allowMultiframe%22%3Afalse%7D%2C%22TextAlignment%22%3A%7B%22alignment%22%3A1%7D%2C%22TextGeometry%22%3A%7B%22type%22%3A2%2C%22damaged%22%3Atrue%2C%22width%22%3A551.7562255859375%2C%22height%22%3A360.8927307128906%2C%22baselineOffset%22%3A0%7D%2C%22TextModel%22%3A%7B%22text%22%3A%22Before%20you%20apply%20or%20renew%20your%20driver%E2%80%99s%20license%2C%20make%20sure%20to%20check%20the%20exact%20date%20listed%20on%20your%20work%20permit%20or%20immigration%20notice%20to%20confirm%20you%20are%20eligible%20for%20a%20license.%5Cu0003%5Cu0003If%20you%E2%80%99re%20unsure%20about%20what%20you%20need%20to%20process%20or%20renew%20your%20license%2C%20visit%20the%20motor%20vehicles%20department%20closest%20to%20your%20home%20for%20official%20guidance.%22%2C%22styles%22%3A%7B%22ranges%22%3A%5B%7B%22charStyle%22%3A%7B%22assigned%22%3A493%2C%22font%22%3A%7B%22source%22%3A%22AF%22%2C%22id%22%3A%22TkD-37516-9d7b232dfcf705029e0147542746f012c505492a%22%2C%22postscriptName%22%3A%22Poppins-Regular%22%2C%22family%22%3A%22Poppins%22%2C%22style%22%3A%22Regular%22%7D%2C%22originalFont%22%3A%7B%22source%22%3A%22AF%22%2C%22id%22%3A%22TkD-37516-9d7b232dfcf705029e0147542746f012c505492a%22%2C%22postscriptName%22%3A%22Poppins-Regular%22%2C%22family%22%3A%22Poppins%22%2C%22style%22%3A%22Regular%22%7D%2C%22fontSize%22%3A29.343280792236328%2C%22color%22%3A%7B%22a%22%3A1%2C%22r%22%3A1%2C%22g%22%3A1%2C%22b%22%3A1%7D%2C%22strikethrough%22%3Afalse%2C%22tracking%22%3A0%2C%22underline%22%3Afalse%2C%22features%22%3A%5B%5D%2C%22textScript%22%3A0%7D%2C%22length%22%3A326%7D%5D%2C%22paragraphs%22%3A%5B%7B%22style%22%3A%7B%22leading%22%3A%7B%22amount%22%3A1.1100000143051147%2C%22type%22%3A1%7D%2C%22listStyle%22%3A%7B%22listId%22%3A%22%22%2C%22listLevel%22%3A0%7D%2C%22direction%22%3A0%2C%22spaceAfter%22%3A0%2C%22spaceBefore%22%3A0%2C%22assigned%22%3A15%7D%2C%22length%22%3A175%7D%2C%7B%22style%22%3A%7B%22leading%22%3A%7B%22amount%22%3A1.1100000143051147%2C%22type%22%3A1%7D%2C%22listStyle%22%3A%7B%22listId%22%3A%22%22%2C%22listLevel%22%3A0%7D%2C%22direction%22%3A0%2C%22spaceAfter%22%3A0%2C%22spaceBefore%22%3A0%2C%22assigned%22%3A15%7D%2C%22length%22%3A1%7D%2C%7B%22style%22%3A%7B%22leading%22%3A%7B%22amount%22%3A1.1100000143051147%2C%22type%22%3A1%7D%2C%22listStyle%22%3A%7B%22listId%22%3A%22%22%2C%22listLevel%22%3A0%7D%2C%22direction%22%3A0%2C%22spaceAfter%22%3A0%2C%22spaceBefore%22%3A0%2C%22assigned%22%3A15%7D%2C%22length%22%3A150%7D%5D%2C%22listStyles%22%3A%5B%5D%7D%2C%22objectStyle%22%3A%7B%22languageLayoutProfile%22%3A%7B%22name%22%3A%22langDefault%22%2C%22version%22%3A1%7D%7D%7D%2C%22TextDefaultValueChanged%22%3A%7B%7D%2C%22TextForwardReferencesMap%22%3A%7B%22entityIdMapping%22%3A%7B%7D%7D%2C%22ArtboardRelativeSceneNodeTransform%22%3A%7B%22x%22%3A123.47265625%2C%22y%22%3A621.4978637695312%2C%22rotation%22%3A0%7D%2C%22CopyPastePixelInformation%22%3A%7B%22density%22%3A96%7D%7D%7D%2C%22version%22%3A360%2C%22draftDocumentModels%22%3A%22%22%7D%2C%22entityIds%22%3A%5B%22d0f907c6-2b53-40aa-bc2b-39ab00115b50%22%5D%7D%2C%22metadata%22%3A%7B%22sourceContext%22%3A%229e247c53-8fcb-486b-8e63-c29a2361ec67%22%7D%7D(\/Adobe)--&gt;\">Before you apply or renew your driver\u2019s license, make sure to check the exact date listed on your work permit or immigration notice to confirm you are eligible for a license.\u0003\u0003If you\u2019re unsure about what you need to process or renew your license, visit the motor vehicles department closest to your home for official guidance.<\/span><\/p>\n<h2><span data-buffer=\"&lt;!--(Adobe)%7B%22type%22%3A%22horizonObject%22%2C%22payload%22%3A%7B%22docId%22%3A%22urn%3Aaaid%3Asc%3AUS%3A8681444c-8303-573a-b790-8847c2c7c635%22%2C%22repositoryId%22%3A%22urn%3Aaaid%3Asc%3AUS%3A7f347c18-c8a3-52e5-8bb6-5722e61eca28%22%2C%22copyClientId%22%3A%227e93896b-cf25-4627-a556-963a884a22fc%22%2C%22docModel%22%3A%7B%22isFullDocument%22%3Afalse%2C%22serializedECS%22%3A%7B%22AssetInfo%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22BitmapReference%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ForwardReference%22%3A%7B%7D%7D%2C%22BitmapRole%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22BlendMode%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22CanvasColor%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ContentCredentialsMetadata%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22LinkedAssetMetadata%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22EllipseGeometry%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22FillChildOf%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ChildOf%22%3A%7B%7D%7D%2C%22FillColor%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22IsColor%22%3A%7B%7D%7D%2C%22FillTransform%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22FillType%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ImageSaliencyMetadata%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22InvisibleBoundingBox%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22IsCropGroup%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22LineGeometry%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22MarkedForImport%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ObjectFit%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22PixelInformation%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22RectangleCornerRadii%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22RectangleGeometry%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceAvailability%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceHasCaiData%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceChildOf%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ChildOf%22%3A%7B%7D%7D%2C%22ResourceCollectionChildOf%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ChildOf%22%3A%7B%7D%2C%22WeakChildOf%22%3A%7B%7D%7D%2C%22ResourceCollectionInfo%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceCollectionOriginalContentHashSHA1%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceCollectionOriginalFileName%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceCollectionOriginalMimeType%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceCollectionOriginalResourceSize%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceDimensions%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceInfo%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceNeedsPublishing%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourcePreferredPixelFormat%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceUrl%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeAspectLock%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeChildOf%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ChildOf%22%3A%7B%7D%7D%2C%22SceneNodeLockCurrent%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22AffectsEditabilityTrait%22%3A%7B%7D%7D%2C%22SceneNodeLockMinimum%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeName%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeOpacity%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeTransform%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeType%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22slot%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeCap%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeChildOf%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ChildOf%22%3A%7B%7D%7D%2C%22StrokeColor%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22IsColor%22%3A%7B%7D%7D%2C%22StrokeDashGeometry%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeJoin%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeMiter%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokePosition%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeType%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeWidth%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SourceAssetIdentifier%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22TimingInfo%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22VisibleBoundingBox%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22XMPMetadata%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22BatchCreateDataMapping%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeAncestorLockState%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22AffectsEditabilityTrait%22%3A%7B%7D%7D%2C%22%23decoration%22%3A%7B%22NonPersistable%22%3A%7B%7D%7D%2C%22%23canvas%22%3A%7B%22NonPersistable%22%3A%7B%7D%7D%2C%22%23effects%22%3A%7B%22NonPersistable%22%3A%7B%7D%7D%2C%22ResourceIsUploading%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22PendingSave%22%3A%7B%7D%7D%2C%22ResourceCollectionIsStoringInIDB%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22PendingSave%22%3A%7B%7D%7D%2C%223e53b815-10d5-47b7-b7f4-d12cae5dd36a%22%3A%7B%22SceneNodeTransform%22%3A%7B%22x%22%3A485.5553894042969%2C%22y%22%3A787.4752807617188%2C%22rotation%22%3A0%2C%22scaleX%22%3A1.3333333333333333%2C%22scaleY%22%3A1.3333333333333333%7D%2C%22SceneNodeType%22%3A%7B%22type%22%3A%22Text%22%7D%2C%22TextType%22%3A%7B%22allowMultiframe%22%3Afalse%7D%2C%22TextAlignment%22%3A%7B%22alignment%22%3A3%7D%2C%22TextGeometry%22%3A%7B%22type%22%3A2%2C%22damaged%22%3Atrue%2C%22width%22%3A396.2698669433594%2C%22height%22%3A63.98902225494385%2C%22baselineOffset%22%3A0%7D%2C%22TextModel%22%3A%7B%22text%22%3A%22Get%20in%20touch%20with%20us!%22%2C%22styles%22%3A%7B%22ranges%22%3A%5B%7B%22charStyle%22%3A%7B%22assigned%22%3A495%2C%22font%22%3A%7B%22source%22%3A%22AF%22%2C%22id%22%3A%22TkD-37900-2fcb08c1acb10c553a809c1b259a7f5ebaa037cc%22%2C%22postscriptName%22%3A%22BebasNeueBold%22%2C%22family%22%3A%22Bebas%20Neue%22%2C%22style%22%3A%22Bold%22%7D%2C%22originalFont%22%3A%7B%22source%22%3A%22AF%22%2C%22id%22%3A%22TkD-37900-2fcb08c1acb10c553a809c1b259a7f5ebaa037cc%22%2C%22postscriptName%22%3A%22BebasNeueBold%22%2C%22family%22%3A%22Bebas%20Neue%22%2C%22style%22%3A%22Bold%22%7D%2C%22fontSize%22%3A58.17232131958008%2C%22color%22%3A%7B%22a%22%3A1%2C%22r%22%3A1%2C%22g%22%3A1%2C%22b%22%3A1%7D%2C%22strikethrough%22%3Afalse%2C%22tracking%22%3A0%2C%22underline%22%3Afalse%2C%22features%22%3A%5B%5D%2C%22textScript%22%3A0%7D%2C%22length%22%3A21%7D%5D%2C%22paragraphs%22%3A%5B%7B%22style%22%3A%7B%22leading%22%3A%7B%22amount%22%3A0.9900000095367432%2C%22type%22%3A1%7D%2C%22listStyle%22%3A%7B%22listId%22%3A%22%22%2C%22listLevel%22%3A0%7D%2C%22direction%22%3A0%2C%22spaceAfter%22%3A0%2C%22spaceBefore%22%3A0%2C%22assigned%22%3A15%7D%2C%22length%22%3A21%7D%5D%2C%22listStyles%22%3A%5B%5D%7D%2C%22objectStyle%22%3A%7B%22languageLayoutProfile%22%3A%7B%22name%22%3A%22langDefault%22%2C%22version%22%3A1%7D%7D%7D%2C%22TextDefaultValueChanged%22%3A%7B%7D%2C%22TextForwardReferencesMap%22%3A%7B%22entityIdMapping%22%3A%7B%7D%7D%2C%22ArtboardRelativeSceneNodeTransform%22%3A%7B%22x%22%3A485.5553894042969%2C%22y%22%3A787.4752807617188%2C%22rotation%22%3A0%7D%2C%22CopyPastePixelInformation%22%3A%7B%22density%22%3A96%7D%7D%7D%2C%22version%22%3A360%2C%22draftDocumentModels%22%3A%22%22%7D%2C%22entityIds%22%3A%5B%223e53b815-10d5-47b7-b7f4-d12cae5dd36a%22%5D%7D%2C%22metadata%22%3A%7B%22sourceContext%22%3A%22ddd89db3-e274-45da-8f3c-f7a0ae8b7345%22%7D%7D(\/Adobe)--&gt;\">Get in touch with us!<\/span><\/h2>\n<p><span data-buffer=\"&lt;!--(Adobe)%7B%22type%22%3A%22horizonObject%22%2C%22payload%22%3A%7B%22docId%22%3A%22urn%3Aaaid%3Asc%3AUS%3A8681444c-8303-573a-b790-8847c2c7c635%22%2C%22repositoryId%22%3A%22urn%3Aaaid%3Asc%3AUS%3A7f347c18-c8a3-52e5-8bb6-5722e61eca28%22%2C%22copyClientId%22%3A%227e93896b-cf25-4627-a556-963a884a22fc%22%2C%22docModel%22%3A%7B%22isFullDocument%22%3Afalse%2C%22serializedECS%22%3A%7B%22AssetInfo%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22BitmapReference%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ForwardReference%22%3A%7B%7D%7D%2C%22BitmapRole%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22BlendMode%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22CanvasColor%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ContentCredentialsMetadata%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22LinkedAssetMetadata%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22EllipseGeometry%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22FillChildOf%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ChildOf%22%3A%7B%7D%7D%2C%22FillColor%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22IsColor%22%3A%7B%7D%7D%2C%22FillTransform%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22FillType%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ImageSaliencyMetadata%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22InvisibleBoundingBox%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22IsCropGroup%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22LineGeometry%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22MarkedForImport%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ObjectFit%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22PixelInformation%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22RectangleCornerRadii%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22RectangleGeometry%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceAvailability%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceHasCaiData%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceChildOf%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ChildOf%22%3A%7B%7D%7D%2C%22ResourceCollectionChildOf%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ChildOf%22%3A%7B%7D%2C%22WeakChildOf%22%3A%7B%7D%7D%2C%22ResourceCollectionInfo%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceCollectionOriginalContentHashSHA1%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceCollectionOriginalFileName%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceCollectionOriginalMimeType%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceCollectionOriginalResourceSize%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceDimensions%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceInfo%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceNeedsPublishing%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourcePreferredPixelFormat%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22ResourceUrl%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeAspectLock%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeChildOf%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ChildOf%22%3A%7B%7D%7D%2C%22SceneNodeLockCurrent%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22AffectsEditabilityTrait%22%3A%7B%7D%7D%2C%22SceneNodeLockMinimum%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeName%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeOpacity%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeTransform%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeType%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22slot%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeCap%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeChildOf%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22ChildOf%22%3A%7B%7D%7D%2C%22StrokeColor%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%2C%22IsColor%22%3A%7B%7D%7D%2C%22StrokeDashGeometry%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeJoin%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeMiter%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokePosition%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeType%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22StrokeWidth%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SourceAssetIdentifier%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22TimingInfo%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22VisibleBoundingBox%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22XMPMetadata%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22BatchCreateDataMapping%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22Persistable%22%3A%7B%7D%7D%2C%22SceneNodeAncestorLockState%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22AffectsEditabilityTrait%22%3A%7B%7D%7D%2C%22%23decoration%22%3A%7B%22NonPersistable%22%3A%7B%7D%7D%2C%22%23canvas%22%3A%7B%22NonPersistable%22%3A%7B%7D%7D%2C%22%23effects%22%3A%7B%22NonPersistable%22%3A%7B%7D%7D%2C%22ResourceIsUploading%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22PendingSave%22%3A%7B%7D%7D%2C%22ResourceCollectionIsStoringInIDB%22%3A%7B%22ComponentWithTrait%22%3A%7B%7D%2C%22PendingSave%22%3A%7B%7D%7D%2C%224dc59ca7-7bff-4f0d-8e8b-e33ce5d69f70%22%3A%7B%22SceneNodeTransform%22%3A%7B%22x%22%3A97.24609375%2C%22y%22%3A508.74493408203125%2C%22rotation%22%3A0%2C%22scaleX%22%3A1.3333333333333333%2C%22scaleY%22%3A1.3333333333333333%7D%2C%22SceneNodeType%22%3A%7B%22type%22%3A%22Text%22%7D%2C%22TextType%22%3A%7B%22allowMultiframe%22%3Afalse%7D%2C%22TextAlignment%22%3A%7B%22alignment%22%3A3%7D%2C%22TextGeometry%22%3A%7B%22type%22%3A2%2C%22damaged%22%3Atrue%2C%22width%22%3A568.9239501953125%2C%22height%22%3A97.9952392578125%2C%22baselineOffset%22%3A0%7D%2C%22TextModel%22%3A%7B%22text%22%3A%22If%20you%20have%20questions%20about%20your%20status%20or%20work%20permits%20after%20TPS%20ends%2C%5Crreach%20out%20to%20us%20for%20expert%20guidance.%22%2C%22styles%22%3A%7B%22ranges%22%3A%5B%7B%22charStyle%22%3A%7B%22assigned%22%3A493%2C%22font%22%3A%7B%22source%22%3A%22AF%22%2C%22id%22%3A%22TkD-37516-9d7b232dfcf705029e0147542746f012c505492a%22%2C%22postscriptName%22%3A%22Poppins-Regular%22%2C%22family%22%3A%22Poppins%22%2C%22style%22%3A%22Regular%22%7D%2C%22originalFont%22%3A%7B%22source%22%3A%22AF%22%2C%22id%22%3A%22TkD-37516-9d7b232dfcf705029e0147542746f012c505492a%22%2C%22postscriptName%22%3A%22Poppins-Regular%22%2C%22family%22%3A%22Poppins%22%2C%22style%22%3A%22Regular%22%7D%2C%22fontSize%22%3A28.83069610595703%2C%22color%22%3A%7B%22a%22%3A1%2C%22r%22%3A1%2C%22g%22%3A1%2C%22b%22%3A1%7D%2C%22strikethrough%22%3Afalse%2C%22tracking%22%3A0%2C%22underline%22%3Afalse%2C%22features%22%3A%5B%5D%2C%22textScript%22%3A0%7D%2C%22length%22%3A108%7D%5D%2C%22paragraphs%22%3A%5B%7B%22style%22%3A%7B%22leading%22%3A%7B%22amount%22%3A1.100000023841858%2C%22type%22%3A1%7D%2C%22listStyle%22%3A%7B%22listId%22%3A%22%22%2C%22listLevel%22%3A0%7D%2C%22direction%22%3A0%2C%22spaceAfter%22%3A0%2C%22spaceBefore%22%3A0%2C%22assigned%22%3A15%7D%2C%22length%22%3A72%7D%2C%7B%22style%22%3A%7B%22leading%22%3A%7B%22amount%22%3A1.100000023841858%2C%22type%22%3A1%7D%2C%22listStyle%22%3A%7B%22listId%22%3A%22%22%2C%22listLevel%22%3A0%7D%2C%22direction%22%3A0%2C%22spaceAfter%22%3A0%2C%22spaceBefore%22%3A0%2C%22assigned%22%3A15%7D%2C%22length%22%3A36%7D%5D%2C%22listStyles%22%3A%5B%5D%7D%2C%22objectStyle%22%3A%7B%22languageLayoutProfile%22%3A%7B%22name%22%3A%22langDefault%22%2C%22version%22%3A1%7D%7D%7D%2C%22TextDefaultValueChanged%22%3A%7B%7D%2C%22TextForwardReferencesMap%22%3A%7B%22entityIdMapping%22%3A%7B%7D%7D%2C%22ArtboardRelativeSceneNodeTransform%22%3A%7B%22x%22%3A97.24609375%2C%22y%22%3A508.74493408203125%2C%22rotation%22%3A0%7D%2C%22CopyPastePixelInformation%22%3A%7B%22density%22%3A96%7D%7D%7D%2C%22version%22%3A360%2C%22draftDocumentModels%22%3A%22%22%7D%2C%22entityIds%22%3A%5B%224dc59ca7-7bff-4f0d-8e8b-e33ce5d69f70%22%5D%7D%2C%22metadata%22%3A%7B%22sourceContext%22%3A%22ddd89db3-e274-45da-8f3c-f7a0ae8b7345%22%7D%7D(\/Adobe)--&gt;\">If you have questions about your status or work permits after TPS ends, reach out to us for expert guidance.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Miami-Dade Tax Collector Dariel Fernandez has announced new guidelines for driver\u2019s licenses for Venezuelan citizens under TPS, as outlined by the Florida Department of Highway Safety and Motor Vehicles.\u0003 Be sure to check the key dates listed on your work permit or immigration notice. Licenses valid until October 2026 If your work permit or immigration [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":53173,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203,120],"tags":[],"class_list":["post-53172","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-en","category-immigration-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>TPS Venezuela: \u0003Driver\u2019s License in florida - Jesus Reyes Law<\/title>\n<meta name=\"description\" content=\"Obt\u00e9n informaci\u00f3n actualizada sobre la licencia de conducir en Florida para ciudadanos venezolanos bajo TPS. Fechas clave incluidas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jesusreyeslaw.com\/en\/tps-venezuela-drivers-license-in-florida\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TPS Venezuela: \u0003Driver\u2019s License in florida\" \/>\n<meta property=\"og:description\" content=\"Obt\u00e9n informaci\u00f3n actualizada sobre la licencia de conducir en Florida para ciudadanos venezolanos bajo TPS. Fechas clave incluidas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jesusreyeslaw.com\/en\/tps-venezuela-drivers-license-in-florida\/\" \/>\n<meta property=\"og:site_name\" content=\"Jesus Reyes Law\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-23T21:21:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-23T21:25:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jesusreyeslaw.com\/wp-content\/uploads\/2025\/10\/ID-TPS-14.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"562\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Wilmer Hurtado\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Wilmer Hurtado\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jesusreyeslaw.com\\\/en\\\/tps-venezuela-drivers-license-in-florida\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jesusreyeslaw.com\\\/en\\\/tps-venezuela-drivers-license-in-florida\\\/\"},\"author\":{\"name\":\"Wilmer Hurtado\",\"@id\":\"https:\\\/\\\/jesusreyeslaw.com\\\/en\\\/#\\\/schema\\\/person\\\/ba3b31253a8ab7e9e4c357019e80c41f\"},\"headline\":\"TPS Venezuela: \\u0003Driver\u2019s License in florida\",\"datePublished\":\"2025-10-23T21:21:11+00:00\",\"dateModified\":\"2025-10-23T21:25:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jesusreyeslaw.com\\\/en\\\/tps-venezuela-drivers-license-in-florida\\\/\"},\"wordCount\":185,\"publisher\":{\"@id\":\"https:\\\/\\\/jesusreyeslaw.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jesusreyeslaw.com\\\/en\\\/tps-venezuela-drivers-license-in-florida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jesusreyeslaw.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ID-TPS-14.webp\",\"articleSection\":[\"Blog\",\"Immigration News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jesusreyeslaw.com\\\/en\\\/tps-venezuela-drivers-license-in-florida\\\/\",\"url\":\"https:\\\/\\\/jesusreyeslaw.com\\\/en\\\/tps-venezuela-drivers-license-in-florida\\\/\",\"name\":\"TPS Venezuela: \\u0003Driver\u2019s License in florida - Jesus Reyes Law\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jesusreyeslaw.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jesusreyeslaw.com\\\/en\\\/tps-venezuela-drivers-license-in-florida\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jesusreyeslaw.com\\\/en\\\/tps-venezuela-drivers-license-in-florida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jesusreyeslaw.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ID-TPS-14.webp\",\"datePublished\":\"2025-10-23T21:21:11+00:00\",\"dateModified\":\"2025-10-23T21:25:30+00:00\",\"description\":\"Obt\u00e9n informaci\u00f3n actualizada sobre la licencia de conducir en Florida para ciudadanos venezolanos bajo TPS. Fechas clave incluidas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jesusreyeslaw.com\\\/en\\\/tps-venezuela-drivers-license-in-florida\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jesusreyeslaw.com\\\/en\\\/tps-venezuela-drivers-license-in-florida\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/jesusreyeslaw.com\\\/en\\\/tps-venezuela-drivers-license-in-florida\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jesusreyeslaw.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ID-TPS-14.webp\",\"contentUrl\":\"https:\\\/\\\/jesusreyeslaw.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ID-TPS-14.webp\",\"width\":1000,\"height\":562},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jesusreyeslaw.com\\\/en\\\/tps-venezuela-drivers-license-in-florida\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jesusreyeslaw.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TPS Venezuela: \\u0003Driver\u2019s License in florida\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jesusreyeslaw.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/jesusreyeslaw.com\\\/en\\\/\",\"name\":\"Jesus Reyes Law\",\"description\":\"Law office of Jesus Reyes. Immigration Attorneys Miami FL\",\"publisher\":{\"@id\":\"https:\\\/\\\/jesusreyeslaw.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jesusreyeslaw.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jesusreyeslaw.com\\\/en\\\/#organization\",\"name\":\"Jesus Reyes Law\",\"url\":\"https:\\\/\\\/jesusreyeslaw.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/jesusreyeslaw.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jesusreyeslaw.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Logo-website-01-01.svg\",\"contentUrl\":\"https:\\\/\\\/jesusreyeslaw.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Logo-website-01-01.svg\",\"caption\":\"Jesus Reyes Law\"},\"image\":{\"@id\":\"https:\\\/\\\/jesusreyeslaw.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jesusreyeslaw.com\\\/en\\\/#\\\/schema\\\/person\\\/ba3b31253a8ab7e9e4c357019e80c41f\",\"name\":\"Wilmer Hurtado\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b64dc255b66e5525db6349038ea338463721611b067595e93ce9558272c9ffd5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b64dc255b66e5525db6349038ea338463721611b067595e93ce9558272c9ffd5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b64dc255b66e5525db6349038ea338463721611b067595e93ce9558272c9ffd5?s=96&d=mm&r=g\",\"caption\":\"Wilmer Hurtado\"},\"url\":\"https:\\\/\\\/jesusreyeslaw.com\\\/en\\\/author\\\/jesus-reyes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"TPS Venezuela: \u0003Driver\u2019s License in florida - Jesus Reyes Law","description":"Obt\u00e9n informaci\u00f3n actualizada sobre la licencia de conducir en Florida para ciudadanos venezolanos bajo TPS. Fechas clave incluidas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jesusreyeslaw.com\/en\/tps-venezuela-drivers-license-in-florida\/","og_locale":"en_US","og_type":"article","og_title":"TPS Venezuela: \u0003Driver\u2019s License in florida","og_description":"Obt\u00e9n informaci\u00f3n actualizada sobre la licencia de conducir en Florida para ciudadanos venezolanos bajo TPS. Fechas clave incluidas.","og_url":"https:\/\/jesusreyeslaw.com\/en\/tps-venezuela-drivers-license-in-florida\/","og_site_name":"Jesus Reyes Law","article_published_time":"2025-10-23T21:21:11+00:00","article_modified_time":"2025-10-23T21:25:30+00:00","og_image":[{"width":1000,"height":562,"url":"https:\/\/jesusreyeslaw.com\/wp-content\/uploads\/2025\/10\/ID-TPS-14.webp","type":"image\/webp"}],"author":"Wilmer Hurtado","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Wilmer Hurtado","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jesusreyeslaw.com\/en\/tps-venezuela-drivers-license-in-florida\/#article","isPartOf":{"@id":"https:\/\/jesusreyeslaw.com\/en\/tps-venezuela-drivers-license-in-florida\/"},"author":{"name":"Wilmer Hurtado","@id":"https:\/\/jesusreyeslaw.com\/en\/#\/schema\/person\/ba3b31253a8ab7e9e4c357019e80c41f"},"headline":"TPS Venezuela: \u0003Driver\u2019s License in florida","datePublished":"2025-10-23T21:21:11+00:00","dateModified":"2025-10-23T21:25:30+00:00","mainEntityOfPage":{"@id":"https:\/\/jesusreyeslaw.com\/en\/tps-venezuela-drivers-license-in-florida\/"},"wordCount":185,"publisher":{"@id":"https:\/\/jesusreyeslaw.com\/en\/#organization"},"image":{"@id":"https:\/\/jesusreyeslaw.com\/en\/tps-venezuela-drivers-license-in-florida\/#primaryimage"},"thumbnailUrl":"https:\/\/jesusreyeslaw.com\/wp-content\/uploads\/2025\/10\/ID-TPS-14.webp","articleSection":["Blog","Immigration News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/jesusreyeslaw.com\/en\/tps-venezuela-drivers-license-in-florida\/","url":"https:\/\/jesusreyeslaw.com\/en\/tps-venezuela-drivers-license-in-florida\/","name":"TPS Venezuela: \u0003Driver\u2019s License in florida - Jesus Reyes Law","isPartOf":{"@id":"https:\/\/jesusreyeslaw.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jesusreyeslaw.com\/en\/tps-venezuela-drivers-license-in-florida\/#primaryimage"},"image":{"@id":"https:\/\/jesusreyeslaw.com\/en\/tps-venezuela-drivers-license-in-florida\/#primaryimage"},"thumbnailUrl":"https:\/\/jesusreyeslaw.com\/wp-content\/uploads\/2025\/10\/ID-TPS-14.webp","datePublished":"2025-10-23T21:21:11+00:00","dateModified":"2025-10-23T21:25:30+00:00","description":"Obt\u00e9n informaci\u00f3n actualizada sobre la licencia de conducir en Florida para ciudadanos venezolanos bajo TPS. Fechas clave incluidas.","breadcrumb":{"@id":"https:\/\/jesusreyeslaw.com\/en\/tps-venezuela-drivers-license-in-florida\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jesusreyeslaw.com\/en\/tps-venezuela-drivers-license-in-florida\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/jesusreyeslaw.com\/en\/tps-venezuela-drivers-license-in-florida\/#primaryimage","url":"https:\/\/jesusreyeslaw.com\/wp-content\/uploads\/2025\/10\/ID-TPS-14.webp","contentUrl":"https:\/\/jesusreyeslaw.com\/wp-content\/uploads\/2025\/10\/ID-TPS-14.webp","width":1000,"height":562},{"@type":"BreadcrumbList","@id":"https:\/\/jesusreyeslaw.com\/en\/tps-venezuela-drivers-license-in-florida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jesusreyeslaw.com\/en\/"},{"@type":"ListItem","position":2,"name":"TPS Venezuela: \u0003Driver\u2019s License in florida"}]},{"@type":"WebSite","@id":"https:\/\/jesusreyeslaw.com\/en\/#website","url":"https:\/\/jesusreyeslaw.com\/en\/","name":"Jesus Reyes Law","description":"Law office of Jesus Reyes. Immigration Attorneys Miami FL","publisher":{"@id":"https:\/\/jesusreyeslaw.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jesusreyeslaw.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/jesusreyeslaw.com\/en\/#organization","name":"Jesus Reyes Law","url":"https:\/\/jesusreyeslaw.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/jesusreyeslaw.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/jesusreyeslaw.com\/wp-content\/uploads\/2020\/11\/Logo-website-01-01.svg","contentUrl":"https:\/\/jesusreyeslaw.com\/wp-content\/uploads\/2020\/11\/Logo-website-01-01.svg","caption":"Jesus Reyes Law"},"image":{"@id":"https:\/\/jesusreyeslaw.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/jesusreyeslaw.com\/en\/#\/schema\/person\/ba3b31253a8ab7e9e4c357019e80c41f","name":"Wilmer Hurtado","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/b64dc255b66e5525db6349038ea338463721611b067595e93ce9558272c9ffd5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b64dc255b66e5525db6349038ea338463721611b067595e93ce9558272c9ffd5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b64dc255b66e5525db6349038ea338463721611b067595e93ce9558272c9ffd5?s=96&d=mm&r=g","caption":"Wilmer Hurtado"},"url":"https:\/\/jesusreyeslaw.com\/en\/author\/jesus-reyes\/"}]}},"_links":{"self":[{"href":"https:\/\/jesusreyeslaw.com\/en\/wp-json\/wp\/v2\/posts\/53172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jesusreyeslaw.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jesusreyeslaw.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jesusreyeslaw.com\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/jesusreyeslaw.com\/en\/wp-json\/wp\/v2\/comments?post=53172"}],"version-history":[{"count":1,"href":"https:\/\/jesusreyeslaw.com\/en\/wp-json\/wp\/v2\/posts\/53172\/revisions"}],"predecessor-version":[{"id":53174,"href":"https:\/\/jesusreyeslaw.com\/en\/wp-json\/wp\/v2\/posts\/53172\/revisions\/53174"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jesusreyeslaw.com\/en\/wp-json\/wp\/v2\/media\/53173"}],"wp:attachment":[{"href":"https:\/\/jesusreyeslaw.com\/en\/wp-json\/wp\/v2\/media?parent=53172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jesusreyeslaw.com\/en\/wp-json\/wp\/v2\/categories?post=53172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jesusreyeslaw.com\/en\/wp-json\/wp\/v2\/tags?post=53172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}